{"id":1026,"date":"2023-08-23T07:28:08","date_gmt":"2023-08-23T07:28:08","guid":{"rendered":"https:\/\/srv15-bcrec.in\/?page_id=1026"},"modified":"2023-08-23T07:28:08","modified_gmt":"2023-08-23T07:28:08","slug":"csd-semester-4","status":"publish","type":"page","link":"https:\/\/srv15-bcrec.in\/feedback\/csd-semester-4\/","title":{"rendered":"CSD Semester 4"},"content":{"rendered":"<div id=\"pl-1026\"  class=\"panel-layout\" ><div id=\"pg-1026-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-1026-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-1026-0-0-0\" class=\"so-panel widget widget_wpforms-widget wpforms-widget panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-825\"><form id=\"wpforms-form-825\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"825\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/feedback\/wp-json\/wp\/v2\/pages\/1026\" data-token=\"6ebe298ad61c456df8eb86152b330487\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-825-field_44-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"44\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_44\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-825-field_44\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][44]\" required><\/div><div id=\"wpforms-825-field_86-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"86\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_86\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-825-field_86\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][86]\" required><\/div><div id=\"wpforms-825-field_88-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"88\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_88\">University Roll No. <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-825-field_88\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][88]\" required><\/div><div id=\"wpforms-825-field_90-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"90\"><input type=\"hidden\" id=\"wpforms-825-field_90\" name=\"wpforms[fields][90]\" value=\"Computer Science and Design\"><\/div><div id=\"wpforms-825-field_31-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"31\"><input type=\"hidden\" id=\"wpforms-825-field_31\" name=\"wpforms[fields][31]\" value=\"2023-24\"><\/div><div id=\"wpforms-825-field_91-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"91\"><input type=\"hidden\" id=\"wpforms-825-field_91\" name=\"wpforms[fields][91]\" value=\"FOURTH\"><\/div><div id=\"wpforms-825-field_92-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"92\"><input type=\"hidden\" id=\"wpforms-825-field_92\" name=\"wpforms[fields][92]\" value=\"SECOND\"><\/div><div id=\"wpforms-825-field_97-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"97\"><div id=\"wpforms-825-field_97\"><hr><\/div><\/div><div id=\"wpforms-825-field_95-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"95\"><h3 id=\"wpforms-825-field_95\" name=\"wpforms[fields][95]\">Feedback on Teaching Learning<\/h3><\/div><div id=\"wpforms-825-field_98-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"98\"><div id=\"wpforms-825-field_98\"><hr><\/div><\/div><div id=\"wpforms-825-field_96-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"96\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_96\">Subject<\/label><select id=\"wpforms-825-field_96\" class=\"wpforms-field-medium\" name=\"wpforms[fields][96]\"><option value=\"PCC-CSD401 - Computer Graphics &amp; Animation\" >PCC-CSD401 - Computer Graphics &amp; Animation<\/option><option value=\"PCC-CSD402 -Design &amp; Analysis of Algorithms\" >PCC-CSD402 -Design &amp; Analysis of Algorithms<\/option><option value=\"PCC-CSD403 - Object Oriented Programming and Design\" >PCC-CSD403 - Object Oriented Programming and Design<\/option><option value=\"PCC-CSD404 - Computer Networks\" >PCC-CSD404 - Computer Networks<\/option><option value=\"BSC 401 - Biology\" >BSC 401 - Biology<\/option><option value=\"MC401 - Environmental Sciences\" >MC401 - Environmental Sciences<\/option><option value=\"PCC-CSD491 - Computer Graphics &amp; Animation Lab\" >PCC-CSD491 - Computer Graphics &amp; Animation Lab<\/option><option value=\"PCC-CSD492 - Design &amp; Analysis of Algorithms Lab\" >PCC-CSD492 - Design &amp; Analysis of Algorithms Lab<\/option><option value=\"PCC-CSD493 - Object Oriented Programming and Design Lab\" >PCC-CSD493 - Object Oriented Programming and Design Lab<\/option><\/select><\/div><div id=\"wpforms-825-field_102-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"102\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_102\">Faculty name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-825-field_102\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][102]\" required><\/div><div id=\"wpforms-825-field_64-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"64\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_64\">1. Teachers inform you about the relevance of the course to your discipline\/stream and corresponding course outcomes and program outcomes. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_64\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_64_1\" name=\"wpforms[fields][64]\" value=\"4 \u2013 Every time\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_64_1\">4 \u2013 Every time<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_64_2\" name=\"wpforms[fields][64]\" value=\"3 \u2013 Usually\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_64_2\">3 \u2013 Usually<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_64_3\" name=\"wpforms[fields][64]\" value=\"2\u2013 Occasionally\/Sometimes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_64_3\">2\u2013 Occasionally\/Sometimes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_64_4\" name=\"wpforms[fields][64]\" value=\"1 \u2013 Rarely\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_64_4\">1 \u2013 Rarely<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_64_5\" name=\"wpforms[fields][64]\" value=\"0\u2013 Never\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_64_5\">0\u2013 Never<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_51-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"51\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_51\">2. How much of the syllabus was covered in the class? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_51\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_51_1\" name=\"wpforms[fields][51]\" value=\"4 \u2013 85 to 100%\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_51_1\">4 \u2013 85 to 100%<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_51_2\" name=\"wpforms[fields][51]\" value=\"3 \u2013 70 to 84%\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_51_2\">3 \u2013 70 to 84%<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_51_3\" name=\"wpforms[fields][51]\" value=\"2 \u2013 55 to 69%\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_51_3\">2 \u2013 55 to 69%<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_51_4\" name=\"wpforms[fields][51]\" value=\"1\u2013 30 to 54%\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_51_4\">1\u2013 30 to 54%<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_51_5\" name=\"wpforms[fields][51]\" value=\"0 \u2013Below 30%\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_51_5\">0 \u2013Below 30%<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_8-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_8\">3. The teacher\u2019s approach to teaching can best be described as <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_8\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_8_1\" name=\"wpforms[fields][8]\" value=\"4\u2013 Excellent\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_8_1\">4\u2013 Excellent<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_8_2\" name=\"wpforms[fields][8]\" value=\"3 \u2013 Very good\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_8_2\">3 \u2013 Very good<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_8_3\" name=\"wpforms[fields][8]\" value=\"2 \u2013 Good\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_8_3\">2 \u2013 Good<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_8_4\" name=\"wpforms[fields][8]\" value=\"1 \u2013 Fair\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_8_4\">1 \u2013 Fair<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_8_5\" name=\"wpforms[fields][8]\" value=\"0\u2013 Poor\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_8_5\">0\u2013 Poor<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_99-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"99\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_99\">4. The classroom\/lab sessions were interactive. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_99\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_99_1\" name=\"wpforms[fields][99]\" value=\"4 \u2013 Every time\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_99_1\">4 \u2013 Every time<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_99_2\" name=\"wpforms[fields][99]\" value=\"3 \u2013 Usually\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_99_2\">3 \u2013 Usually<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_99_3\" name=\"wpforms[fields][99]\" value=\"2\u2013 Occasionally\/Sometimes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_99_3\">2\u2013 Occasionally\/Sometimes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_99_4\" name=\"wpforms[fields][99]\" value=\"1 \u2013 Rarely\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_99_4\">1 \u2013 Rarely<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_99_5\" name=\"wpforms[fields][99]\" value=\"0\u2013 Never\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_99_5\">0\u2013 Never<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_9-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_9\">5. Fairness of the internal evaluation process by the teacher <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_9\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_9_1\" name=\"wpforms[fields][9]\" value=\"4 \u2013 Always fair\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_9_1\">4 \u2013 Always fair<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_9_2\" name=\"wpforms[fields][9]\" value=\"3 \u2013 Usually fair\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_9_2\">3 \u2013 Usually fair<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_9_3\" name=\"wpforms[fields][9]\" value=\"2 \u2013 Sometimes unfair\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_9_3\">2 \u2013 Sometimes unfair<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_9_4\" name=\"wpforms[fields][9]\" value=\"1 \u2013 Usually unfair\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_9_4\">1 \u2013 Usually unfair<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_9_5\" name=\"wpforms[fields][9]\" value=\"0\u2013 Unfair\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_9_5\">0\u2013 Unfair<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_10-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_10\">6. Was your performance in Continuous Assessments (CA) &amp; Practical Continuous Assessments (PCA) discussed with you? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_10\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_10_1\" name=\"wpforms[fields][10]\" value=\"4 \u2013 Every time\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_10_1\">4 \u2013 Every time<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_10_2\" name=\"wpforms[fields][10]\" value=\"3 \u2013 Usually\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_10_2\">3 \u2013 Usually<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_10_3\" name=\"wpforms[fields][10]\" value=\"2 \u2013 Occasionally\/Sometimes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_10_3\">2 \u2013 Occasionally\/Sometimes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_10_4\" name=\"wpforms[fields][10]\" value=\"1 \u2013 Rarely\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_10_4\">1 \u2013 Rarely<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_10_5\" name=\"wpforms[fields][10]\" value=\"0\u2013 Never\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_10_5\">0\u2013 Never<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_66-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"66\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_66\">7. The teachers illustrate the concepts through examples and applications. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_66\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_66_1\" name=\"wpforms[fields][66]\" value=\"4 \u2013 Every time\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_66_1\">4 \u2013 Every time<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_66_2\" name=\"wpforms[fields][66]\" value=\"3 \u2013 Usually\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_66_2\">3 \u2013 Usually<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_66_3\" name=\"wpforms[fields][66]\" value=\"2 \u2013 Occasionally\/Sometimes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_66_3\">2 \u2013 Occasionally\/Sometimes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_66_4\" name=\"wpforms[fields][66]\" value=\"1 \u2013 Rarely\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_66_4\">1 \u2013 Rarely<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_66_5\" name=\"wpforms[fields][66]\" value=\"0 \u2013 Never\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_66_5\">0 \u2013 Never<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_67-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"67\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_67\">8. The teachers identify your strengths and encourage you with providing right level of challenges. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_67\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_67_1\" name=\"wpforms[fields][67]\" value=\"4 \u2013 Fully\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_67_1\">4 \u2013 Fully<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_67_2\" name=\"wpforms[fields][67]\" value=\"3 \u2013 Reasonably\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_67_2\">3 \u2013 Reasonably<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_67_3\" name=\"wpforms[fields][67]\" value=\"2 \u2013 Partially\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_67_3\">2 \u2013 Partially<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_67_4\" name=\"wpforms[fields][67]\" value=\"1 \u2013 Slightly\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_67_4\">1 \u2013 Slightly<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_67_5\" name=\"wpforms[fields][67]\" value=\"0\u2013 Unable to\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_67_5\">0\u2013 Unable to<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_68-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"68\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_68\">9. Teachers are able to identify your weaknesses and help you to overcome them. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_68\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_68_1\" name=\"wpforms[fields][68]\" value=\"4 \u2013 Every time\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_68_1\">4 \u2013 Every time<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_68_2\" name=\"wpforms[fields][68]\" value=\"3 \u2013 Usually\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_68_2\">3 \u2013 Usually<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_68_3\" name=\"wpforms[fields][68]\" value=\"2 \u2013 Occasionally\/Sometimes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_68_3\">2 \u2013 Occasionally\/Sometimes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_68_4\" name=\"wpforms[fields][68]\" value=\"1 \u2013 Rarely\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_68_4\">1 \u2013 Rarely<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_68_5\" name=\"wpforms[fields][68]\" value=\"0 \u2013 Never\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_68_5\">0 \u2013 Never<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_100-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"100\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_100\">10. Teacher used ICT tools (Projectors\/Screens\/Multimedia demonstration slides, Interactive online tools etc.) while teaching. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_100\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_100_1\" name=\"wpforms[fields][100]\" value=\"4 \u2013 Every time\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_100_1\">4 \u2013 Every time<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_100_2\" name=\"wpforms[fields][100]\" value=\"3 \u2013 Usually\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_100_2\">3 \u2013 Usually<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_100_3\" name=\"wpforms[fields][100]\" value=\"2 \u2013 Occasionally\/Sometimes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_100_3\">2 \u2013 Occasionally\/Sometimes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_100_4\" name=\"wpforms[fields][100]\" value=\"1 \u2013 Rarely\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_100_4\">1 \u2013 Rarely<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_100_5\" name=\"wpforms[fields][100]\" value=\"0 \u2013 Never\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_100_5\">0 \u2013 Never<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_71-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"71\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_71\">11. The knowledge from the course can be applied to solve real life\/industry specific problems\/societal needs. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_71\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_71_1\" name=\"wpforms[fields][71]\" value=\"4 \u2013 Strongly agree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_71_1\">4 \u2013 Strongly agree<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_71_2\" name=\"wpforms[fields][71]\" value=\"3 \u2013 Agree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_71_2\">3 \u2013 Agree<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_71_3\" name=\"wpforms[fields][71]\" value=\"2 \u2013 Occasionally\/Sometimes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_71_3\">2 \u2013 Occasionally\/Sometimes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_71_4\" name=\"wpforms[fields][71]\" value=\"1 \u2013Slightly\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_71_4\">1 \u2013Slightly<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_71_5\" name=\"wpforms[fields][71]\" value=\"0 \u2013 Unable to\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_71_5\">0 \u2013 Unable to<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_75-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-3-columns\" data-field-id=\"75\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_75\">12. The overall quality of teaching-learning process of this subject is very good. <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-825-field_75\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_75_1\" name=\"wpforms[fields][75]\" value=\"4 \u2013Strongly agree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_75_1\">4 \u2013Strongly agree<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_75_2\" name=\"wpforms[fields][75]\" value=\"3 \u2013 Agree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_75_2\">3 \u2013 Agree<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_75_3\" name=\"wpforms[fields][75]\" value=\"2 \u2013 Neutral\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_75_3\">2 \u2013 Neutral<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_75_4\" name=\"wpforms[fields][75]\" value=\"1 \u2013 Disagree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_75_4\">1 \u2013 Disagree<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-825-field_75_5\" name=\"wpforms[fields][75]\" value=\"0 \u2013 Strongly disagree\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-825-field_75_5\">0 \u2013 Strongly disagree<\/label><\/li><\/ul><\/div><div id=\"wpforms-825-field_101-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"101\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_101\">Any specific comments<\/label><input type=\"text\" id=\"wpforms-825-field_101\" class=\"wpforms-field-medium\" name=\"wpforms[fields][101]\" ><\/div><div id=\"wpforms-825-field_17-container\" class=\"wpforms-field wpforms-field-captcha\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-825-field_17\">Captcha <span class=\"wpforms-required-label\">*<\/span><\/label>\t\t\t<div class=\"wpforms-captcha-math\">\n\t\t\t\t<span class=\"wpforms-captcha-equation\">\n\t\t\t\t\t<span class=\"n1\"><\/span>\n\t\t\t\t\t<span class=\"cal\"><\/span>\n\t\t\t\t\t<span class=\"n2\"><\/span>\n\t\t\t\t\t<span class=\"e\">=<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<input type=\"text\" id=\"wpforms-825-field_17\" class=\"wpforms-field-medium wpforms-field-required a\" data-rule-wpf-captcha=\"math\" name=\"wpforms[fields][17][a]\" required>\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][17][cal]\" class=\"cal\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][17][n2]\" class=\"n2\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][17][n1]\" class=\"n1\">\n\t\t\t<\/div>\n\t\t\t<\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"825\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"2\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-825\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img src=\"https:\/\/srv15-bcrec.in\/feedback\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Please enable JavaScript in your browser to complete this form.Name *Email *University Roll No. *Feedback on Teaching LearningSubjectPCC-CSD401 &#8211; Computer Graphics &amp; AnimationPCC-CSD402 -Design &amp; Analysis of AlgorithmsPCC-CSD403 &#8211; Object Oriented Programming and DesignPCC-CSD404 &#8211; Computer NetworksBSC 401 &#8211; BiologyMC401 &#8211; Environmental SciencesPCC-CSD491 &#8211; Computer Graphics &amp; Animation LabPCC-CSD492 &#8211; Design &amp; Analysis of Algorithms [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"wf_page_folders":[9],"_links":{"self":[{"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/pages\/1026"}],"collection":[{"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/comments?post=1026"}],"version-history":[{"count":2,"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/pages\/1026\/revisions"}],"predecessor-version":[{"id":1028,"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/pages\/1026\/revisions\/1028"}],"wp:attachment":[{"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/media?parent=1026"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/srv15-bcrec.in\/feedback\/wp-json\/wp\/v2\/wf_page_folders?post=1026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}